{"id":730,"date":"2024-01-08T09:29:29","date_gmt":"2024-01-08T08:29:29","guid":{"rendered":"https:\/\/staging.blimp.ai\/?page_id=730"},"modified":"2025-10-10T14:45:55","modified_gmt":"2025-10-10T12:45:55","slug":"contacts","status":"publish","type":"page","link":"https:\/\/blimp.ai\/en\/contatti\/","title":{"rendered":"Contacts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"730\" class=\"elementor elementor-730\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a805333 e-flex e-con-boxed e-con e-parent\" data-id=\"a805333\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-35be3c8 e-con-full e-flex e-con e-child\" data-id=\"35be3c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0830b32 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0830b32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vuoi saperne di pi\u00f9? \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8005fe elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"c8005fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il mondo dei dati offre nuove opportunit\u00e0 di crescita per moltissimi settori.&nbsp;\u2028<\/p>\n<p>Entra nel futuro con coraggio e determinazione.\u2028<\/p>\n<p>Cambia le logiche del tuo mercato e offri di pi\u00f9 ai tuoi clienti.\u2028\u2028<\/p>\n<p>Contattaci per avere maggiori informazioni sui nostri prodotti e servizi e conoscere l\u2019offerta di Blimp.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c934d84 elementor-widget elementor-widget-button\" data-id=\"c934d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:info@blimp.ai\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">info@blimp.ai<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6252814 e-con-full e-flex e-con e-child\" data-id=\"6252814\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33bbcb5 elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"33bbcb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Contatti\" aria-label=\"Contatti\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"730\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"33bbcb5\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Contatti | Blimp\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"730\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome e Cognome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-azienda elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[azienda]\" id=\"form-field-azienda\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Azienda\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"10\" placeholder=\"Messaggio\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_1f4ffd6 elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_1f4ffd6\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LeqsXspAAAAADSzAxQ9ZZ0cNrpmKeimgCBoLXE_\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-accettazione elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[accettazione]\" id=\"form-field-accettazione\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-accettazione\">Dichiaro di aver letto la <u><a href=\"https:\/\/blimp.ai\/privacy-policy\/\" target=\"_blank\">Privacy Policy<\/a><\/u><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_c991d42 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_c991d42]\" id=\"form-field-field_c991d42\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_c991d42\">Acconsento al trattamento dei miei dati per l'invio di newsletter come indicato nell'informativa sulla <u><a href=\"https:\/\/blimp.ai\/privacy-policy\/\" target=\"_blank\">Privacy Policy<\/a><\/u><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"16\" viewBox=\"0 0 25 16\" fill=\"none\"><path id=\"Arrow 2\" d=\"M24.7071 8.70711C25.0976 8.31658 25.0976 7.68342 24.7071 7.29289L18.3431 0.928932C17.9526 0.538408 17.3195 0.538408 16.9289 0.928932C16.5384 1.31946 16.5384 1.95262 16.9289 2.34315L22.5858 8L16.9289 13.6569C16.5384 14.0474 16.5384 14.6805 16.9289 15.0711C17.3195 15.4616 17.9526 15.4616 18.3431 15.0711L24.7071 8.70711ZM0 9H24V7H0V9Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03c84eb e-flex e-con-boxed e-con e-parent\" data-id=\"03c84eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-18b3a09 e-con-full e-flex e-con e-child\" data-id=\"18b3a09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11f501b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"11f501b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Dove ci troviamo?<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8448b46 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8448b46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo in centro a Milano, in Via San Martino 12, a pochi minuti dal Duomo.<br \/><br \/>Come raggiungerci?<br \/>I nostri uffici sono vicino a Porta Romana e a 10 minuti a piedi dalla fermata della metro gialla \u201cCrocetta\u201d.<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b9c3e0 e-con-full e-flex e-con e-child\" data-id=\"3b9c3e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e4dccb elementor-widget elementor-widget-google_maps\" data-id=\"3e4dccb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=e-novia&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"e-novia\"\n\t\t\t\t\taria-label=\"e-novia\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c779494 e-flex e-con-boxed e-con e-parent\" data-id=\"c779494\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8643e6c e-flex e-con-boxed e-con e-child\" data-id=\"8643e6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-2193da7 elementor-widget elementor-widget-heading\" data-id=\"2193da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TRUSTED BY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d9afb1 elementor-widget elementor-widget-ucaddon_arrow_navigation\" data-id=\"2d9afb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_arrow_navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Remote Arrows -->\n\t\t<link id='font-awesome-css' href='https:\/\/blimp.ai\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/blimp.ai\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Remote Arrows *\/\n\n.ue-remote-carousel-navigation-wrapper\n{\n  display:flex;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow\n{\n  border:none;\n  border-color:transparent;\n}\n\n.ue-remote-carousel-navigation-wrapper .ue-remote-arrow:hover\n{\n  background-color:transparent;\n \n}\n\n\n#uc_arrow_navigation_elementor_2d9afb1\n{\n  display:inline-flex;\n}\n\n#uc_arrow_navigation_elementor_2d9afb1 .ue-remote-arrow\n{\n  flex-grow:0;\n  flex-shrink:0;\n  transition:0.3s;\n  display:inline-flex;\n  align-items:center;\n  justify-content:center;\n  line-height:1em;\n  cursor:pointer;\n}\n\n\n#uc_arrow_navigation_elementor_2d9afb1 .ue-remote-arrow .ue-carousel-nav-icon\n{\n  transition:0.3s;\n  line-height:1em;\n}\n\n#uc_arrow_navigation_elementor_2d9afb1 .ue-remote-arrow .ue-carousel-nav-icon svg\n{\n  transition:0.3s;\n  height:1em;\n  width:1em;\n}\n\n\n#uc_arrow_navigation_elementor_2d9afb1 .ue-carousel-nav-label\n{\n  transition:0.3s;\n}\n\n#uc_arrow_navigation_elementor_2d9afb1 .uc-disabled{\n\topacity: 0.3;\n}\n\n<\/style>\n\n<div class=\"ue-remote-carousel-navigation-wrapper\">\n<div id=\"uc_arrow_navigation_elementor_2d9afb1\" class=\"ue-remote-carousel-navigation\"  data-parentid='second'>\n  \n  \n  \n\t\n\n  \n \n\n  <div class=\"ue-remote-arrow ue-carousel-next \">\n        <div class=\"ue-carousel-nav-icon\"><i class='fas fa-arrow-right'><\/i><\/div>\n  <\/div>\n  \n  \n<\/div>\n<\/div>\n<!-- end Remote Arrows -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-text-color=\"#8a8a8a\" data-dce-title-color=\"#000000\" class=\"elementor-element elementor-element-6e23b0c elementor-widget elementor-widget-ucaddon_card_carousel\" data-id=\"6e23b0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_card_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Card Carousel -->\n\t\t<link id='owl-carousel-css' href='https:\/\/blimp.ai\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='uc_ac_assets_file_animate_css_77907-css' href='https:\/\/blimp.ai\/wp-content\/uploads\/ac_assets\/uc_classic_carousel\/animate.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Card Carousel *\/\n\n#uc_card_carousel_elementor_6e23b0c-wrapper\n{\n  min-height:1px;\n}\n#uc_card_carousel_elementor_6e23b0c *{\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n}\n\n#uc_card_carousel_elementor_6e23b0c .ue-carousel-item\n{\n  overflow:hidden;\n  transition:0.3s;\n}\n\n#uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_container_holder\n{\n\tdisplay:block;\n\tposition:relative;\n\twidth:100%;\n    box-sizing: border-box;\n}\n#uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_placeholder{\n   position:relative;\n}\n\n#uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_placeholder img, #uc_card_carousel_elementor_6e23b0c .ue_card_carousel_image_overlay\n{\n  transition: all 300ms;\n}\n\n.card_carousel_title\n{\n\tfont-size:21px;\n}\n\n.uc_classic_carousel .uc_classic_carousel_border\n{\n\tdisplay:block;\n    margin:0 auto;\n}\n\n.uc_classic_carousel  .uc_classic_carousel_placeholder img\n{\n\twidth:100%;\n    \n    display:inline-flex;\n}\n.uc_classic_carousel .uc_classic_carousel_content\n{\n  display: flex;\n flex-flow: column nowrap;\n}\n\n.uc_classic_carousel .ue_button\n{\n  margin-top:auto;\n\n}\n\n.uc_classic_carousel .uc_classic_carousel_content .uc_more_btn {\n\tdisplay:inline-block;\n\ttext-decoration:none;\n\ttransition: all 0.5s ease;\n}\n\n\n#uc_card_carousel_elementor_6e23b0c .owl-dots {\noverflow:hidden;\ntext-align:center;\n}\n\n#uc_card_carousel_elementor_6e23b0c .owl-dot {\nborder-radius:50%;\ndisplay:inline-block;\n}\n\n#uc_card_carousel_elementor_6e23b0c .owl-nav .owl-prev,\n#uc_card_carousel_elementor_6e23b0c .owl-nav .owl-next{\n    position:absolute;\n    display:flex;\n  \tjustify-content: center;\n  \talign-items: center;\n    text-align:center;\n}\n\n\n#uc_card_carousel_elementor_6e23b0c .owl-nav .disabled\n{\n    display: none;  \n}\n\n\n#uc_card_carousel_elementor_6e23b0c .ue-item-icon\n{\n  line-height:1em;\n  display:inline-flex;\n  justify-content:center;\n  align-items:center;\n  \n}\n\n#uc_card_carousel_elementor_6e23b0c .ue-item-icon svg\n{\n  height:1em;\n  width:1em;\n}\n\n#uc_card_carousel_elementor_6e23b0c .ue-item-icon-wrapper\n{\n  display:flex;\n}\n\n#uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_container_holder {\n\t max-width: ;\n}\n\n\n\n@media screen and (max-width: 1024px) {\n  #uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_container_holder {\n\t max-width: ;\n  }\n}\n\n@media screen and (max-width: 767px) {\n  #uc_card_carousel_elementor_6e23b0c .uc_classic_carousel_container_holder {\n    max-width: ;\n  }\n}\n\n<\/style>\n\n<div class=\"uc_classic_carousel\" id=\"uc_card_carousel_elementor_6e23b0c-wrapper\">\n        <div class=\"uc_carousel owl-carousel uc-items-wrapper  uc-remote-parent \" id=\"uc_card_carousel_elementor_6e23b0c\"  data-remoteid='second' data-widgetname='Card Carousel' >\n          \t<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-c72bb6d\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/ALESSI-1024x420.png\" alt=\"Alessi logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-2ce0b38\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/AMALFI-1024x420.png\" alt=\"Distretto turistico Amalfi logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-72e8617\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/AMAZON-1024x420.png\" alt=\"Amazon logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-d8a8b45\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/AUSTOGRILL-1024x420.png\" alt=\"Autogrill logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-f3da002\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/AUTOSTRADE-1024x420.png\" alt=\"Autostrade per l&#039;Italia\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-f162070\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/AVIP-1024x420.png\" alt=\"AVIP Italia logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-cd079b7\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/ENEL-1024x420.png\" alt=\"Enel logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-90007f1\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/EPTA-1024x420.png\" alt=\"Epta logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-3e28e80\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/IMEDIA-1024x420.png\" alt=\"Immedya logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-8788b41\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/LEROY-1024x420.png\" alt=\"Leroy Merlin logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-1c3e018\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/Fondazione-Links-e1716305432895.png\" alt=\"Fondazione Links\" width=\"588\" height=\"266\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-52f4d41\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/MEDIAONE-1024x420.png\" alt=\"MediaOne logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-1a632fb\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/MONDADORI-1024x420.png\" alt=\"Mondadori logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-08a5324\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/REALMEDIA-1024x420.png\" alt=\"Real Media logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n<div class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-2b29a62\">\n  <div class=\"ue-carousel-item\">\n      <div class=\"uc_classic_carousel_placeholder\">\n          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blimp.ai\/wp-content\/uploads\/2024\/02\/TIM-1024x420.png\" alt=\"Tim logo\" width=\"1024\" height=\"420\" title=\"Deep tech per il monitoraggio dei dati in ambienti urbani\">\n          <\/div>\n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">\n    \n    \n        \n    \t\n    \n      \n        \n    \n    \t\n    \n    \n    \t\n  <\/div>\n  <\/div>\n<\/div>\n\n      <\/div>\n<\/div>\n<!-- end Card Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vuoi saperne di pi\u00f9? Il mondo dei dati offre nuove opportunit\u00e0 di crescita per moltissimi settori.&nbsp;\u2028 Entra nel futuro con coraggio e determinazione.\u2028 Cambia le logiche del tuo mercato e offri di pi\u00f9 ai tuoi clienti.\u2028\u2028 Contattaci per avere maggiori informazioni sui nostri prodotti e servizi e conoscere l\u2019offerta di Blimp. info@blimp.ai Dove ci troviamo? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-730","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/pages\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/comments?post=730"}],"version-history":[{"count":138,"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/pages\/730\/revisions"}],"predecessor-version":[{"id":15269,"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/pages\/730\/revisions\/15269"}],"wp:attachment":[{"href":"https:\/\/blimp.ai\/en\/wp-json\/wp\/v2\/media?parent=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}